{"id":4871,"date":"2023-05-10T19:12:38","date_gmt":"2023-05-10T19:12:38","guid":{"rendered":"https:\/\/enyevent.com\/index.php\/santiago-de-compostela\/"},"modified":"2024-03-18T21:45:50","modified_gmt":"2024-03-18T21:45:50","slug":"santiago-de-compostela","status":"publish","type":"page","link":"https:\/\/enyevent.com\/fr\/destinations\/santiago-de-compostela\/","title":{"rendered":"Santiago de Compostela"},"content":{"rendered":"<p>[vc_row][vc_column]<style>.ld_spacer_6a04646647122{height:32px;}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a04646647122\"><\/div><style><\/style><div class=\"lqd-tabs lqd-tabs-style-8 d-flex flex-wrap ld_tabs_6a04646659fd0\" data-tabs-options='{\"trigger\":\"click\"}'>\n\n\t<nav class=\"lqd-tabs-nav-wrap\">\n\t\t<ul class=\"reset-ul lqd-tabs-nav d-flex flex-column \" role=\"tablist\"><li data-controls=\"lqd-1682073809060-587281a8-c4b4\" role=\"presentation\" class=\"ld_tab_section-6a04646647332 active\"><a class=\"d-flex align-items-center py-1 mb-2\" href=\"#lqd-1682073809060-587281a8-c4b4\" aria-expanded=\"false\" aria-controls=\"lqd-1682073809060-587281a8-c4b4\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Saint-Jacques-de-Compostelle<\/span><\/a><\/li><li data-controls=\"lqd-1680778113079-572ae9e5-5561\" role=\"presentation\" class=\"ld_tab_section-6a04646647f18\"><a class=\"d-flex align-items-center py-1 mb-2\" href=\"#lqd-1680778113079-572ae9e5-5561\" aria-expanded=\"false\" aria-controls=\"lqd-1680778113079-572ae9e5-5561\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Visites sp\u00e9ciales<\/span><\/a><\/li><li data-controls=\"lqd-1682099693389-70fd6c87-9e9a\" role=\"presentation\" class=\"ld_tab_section-6a0464664a8dc\"><a class=\"d-flex align-items-center py-1 mb-2\" href=\"#lqd-1682099693389-70fd6c87-9e9a\" aria-expanded=\"false\" aria-controls=\"lqd-1682099693389-70fd6c87-9e9a\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Visite \u00e0 v\u00e9lo<\/span><\/a><\/li><li data-controls=\"lqd-1682100880311-e775a2c7-a375\" role=\"presentation\" class=\"ld_tab_section-6a0464664d1dd\"><a class=\"d-flex align-items-center py-1 mb-2\" href=\"#lqd-1682100880311-e775a2c7-a375\" aria-expanded=\"false\" aria-controls=\"lqd-1682100880311-e775a2c7-a375\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Activit\u00e9s sportives<\/span><\/a><\/li><li data-controls=\"lqd-1682100543635-94960ecb-75f1\" role=\"presentation\" class=\"ld_tab_section-6a0464664fbe2\"><a class=\"d-flex align-items-center py-1 mb-2\" href=\"#lqd-1682100543635-94960ecb-75f1\" aria-expanded=\"false\" aria-controls=\"lqd-1682100543635-94960ecb-75f1\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Classes de cuisine<\/span><\/a><\/li><li data-controls=\"lqd-1682098856421-82b74996-23ce\" role=\"presentation\" class=\"ld_tab_section-6a0464665252f\"><a class=\"d-flex align-items-center py-1 mb-2\" href=\"#lqd-1682098856421-82b74996-23ce\" aria-expanded=\"false\" aria-controls=\"lqd-1682098856421-82b74996-23ce\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Santiago \u00e0 cheval<\/span><\/a><\/li><li data-controls=\"lqd-1682101131837-cc7a49bc-07e6\" role=\"presentation\" class=\"ld_tab_section-6a04646654e1f\"><a class=\"d-flex align-items-center py-1 mb-2\" href=\"#lqd-1682101131837-cc7a49bc-07e6\" aria-expanded=\"false\" aria-controls=\"lqd-1682101131837-cc7a49bc-07e6\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Excursions<\/span><\/a><\/li><li data-controls=\"lqd-1682101311230-40f07417-99ab\" role=\"presentation\" class=\"ld_tab_section-6a04646657715\"><a class=\"d-flex align-items-center py-1 mb-2\" href=\"#lqd-1682101311230-40f07417-99ab\" aria-expanded=\"false\" aria-controls=\"lqd-1682101311230-40f07417-99ab\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">D\u00e9gustation de vins<\/span><\/a><\/li><\/ul>\t\t \n\t<\/nav>\n\n\t<div class=\"lqd-tabs-content pl-md-6\"><div id=\"lqd-1682073809060-587281a8-c4b4\" role=\"tabpanel\" class=\"lqd-tabs-pane fade active in\"><style>.ld_fancy_heading_6a04646647409 h5{color:#6ebb1f;}.ld_fancy_heading_6a04646647409 h5 {font-size:25px; } .ld_fancy_heading_6a04646647409 h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a04646647409 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a04646647409 h5 {font-size:25px; } .ld_fancy_heading_6a04646647409 h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a04646647409\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Visitez Saint-Jacques de Compostelle<\/h5><\/div><style>.ld_content_box_6a0464664769e .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a0464664769e\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a0464664769e\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/santiago-compostela.jpeg\" class=\"w-100 invisible\" alt=\"\" srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/santiago-compostela.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/santiago-compostela-300x129.jpeg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" itemprop=\"image\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 Saint-Jacques-de-Compostelle<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Visitez Saint-Jacques de Compostelle<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a04646647a17{height:30px;}@media (min-width: 992px) { .ld_spacer_6a04646647a17{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a04646647a17\"><\/div><style>.ld_fancy_heading_6a04646647b7c h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a04646647b7c .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a04646647b7c h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a04646647b7c\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <strong>Chaque ann\u00e9e, Saint-Jacques-de-Compostelle, capitale de la Galice, accueille des millions de visiteurs du monde entier, tant pour les voyages religieux que pour la beaut\u00e9 des lieux. Le centre-ville historique est class\u00e9 au patrimoine mondial de l&rsquo;UNESCO. Cette cit\u00e9 antique se distingue par son ensemble architectural impressionnant. Cela se refl\u00e8te dans les palais et les \u00e9glises qui bordent les rues comme la c\u00e9l\u00e8bre Cath\u00e9drale, la Coll\u00e9giale Santa Maria la Real de Sar, l&rsquo;Hostal de los Reyes Catolicos, la Casa do Cabildo, et les places de son centre historique, un quartier \u00e0 ne pas manquer.<\/strong><\/h6><\/div><style>.ld_fancy_heading_6a04646647d84 p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a04646647d84 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a04646647d84 p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a04646647d84\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Il est vrai que lorsque l&rsquo;on parle de Saint-Jacques-de-Compostelle, on pense imm\u00e9diatement au c\u00e9l\u00e8bre chemin qui m\u00e8ne les p\u00e8lerins depuis des si\u00e8cles jusqu&rsquo;\u00e0 la cath\u00e9drale de Saint-Jacques-de-Compostelle\u00a0: sans aucun doute l&rsquo;un des voyages les plus puissants et inoubliables \u00e0 travers l&rsquo;Europe. Cette destination offre \u00e9galement une universit\u00e9 dynamique avec plus de 30 000 \u00e9tudiants chaque ann\u00e9e. La vieille ville historique est anim\u00e9e tout au long de l&rsquo;ann\u00e9e avec un large choix de restaurants, bars \u00e0 tapas, pubs et discoth\u00e8ques ; un cadre id\u00e9al pour organiser des activit\u00e9s incentives en c\u0153ur de ville.<\/p>\n<p>En termes de gastronomie, Saint-Jacques-de-Compostelle n&rsquo;a rien \u00e0 envier \u00e0 ses villes voisines, car elle fait partie int\u00e9grante de la culture et est m\u00eame consid\u00e9r\u00e9e comme un art. L&rsquo;offre de restaurants et de bars pour tous les budgets est consid\u00e9rable. Des petits \u00ab bistrots \u00bb familiaux aux restaurants \u00e9toil\u00e9s, des plats traditionnels \u00e0 la cuisine moderne et cr\u00e9ative, avec un point commun : la qualit\u00e9 des produits locaux et des fruits de mer.<\/p>\n<p>La ville est \u00e9galement une destination de culture et de nature, puisque chaque ann\u00e9e, elle propose de nombreux concerts, pi\u00e8ces de th\u00e9\u00e2tre, festivals et expositions que les visiteurs d\u00e9couvriront au Centre galicien d&rsquo;art contemporain, au Mus\u00e9e du peuple galicien ou au Mus\u00e9e du Cath\u00e9drale, mais vous trouverez \u00e9galement de nombreux parcs et jardins dans la ville comme celui de San Lorenzo de Trasouto, et \u00e0 proximit\u00e9 vous pourrez profiter d&rsquo;un pique-nique en for\u00eat ou de jeux d&rsquo;orientation dans la v\u00e9g\u00e9tation exub\u00e9rante.<\/p>\n<p>L&#8217;emplacement fabuleux, les pr\u00e9cieux monuments historiques, la culture et la gastronomie galiciennes font de la ville de Saint-Jacques-de-Compostelle une destination tr\u00e8s appr\u00e9ci\u00e9e et demand\u00e9e pour les voyages d&rsquo;affaires et de loisirs. Cette ville accueille de plus en plus de congr\u00e8s m\u00e9dicaux importants et offre un cadre int\u00e9ressant pour des activit\u00e9s de team building originales.<\/p><\/div><\/div><div id=\"lqd-1680778113079-572ae9e5-5561\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a04646647fed h5{color:#6ebb1f;}.ld_fancy_heading_6a04646647fed h5 {font-size:25px; } .ld_fancy_heading_6a04646647fed h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a04646647fed .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a04646647fed h5 {font-size:25px; } .ld_fancy_heading_6a04646647fed h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a04646647fed\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Visites sp\u00e9ciales<\/h5><\/div><style>.ld_content_box_6a046466481af .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a046466481af\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a046466481af\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 700 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/santiago_de_compostela2.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/santiago_de_compostela2.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/santiago_de_compostela2-300x129.jpeg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" data-aspect=\"2.3333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 Saint-Jacques-de-Compostelle<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Visites sp\u00e9ciales<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a0464664a2ee{height:30px;}@media (min-width: 992px) { .ld_spacer_6a0464664a2ee{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a0464664a2ee\"><\/div><style>.ld_fancy_heading_6a0464664a4a1 h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a0464664a4a1 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a0464664a4a1 h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a0464664a4a1\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <strong>Enyevent DMC vous invite \u00e0 d\u00e9couvrir l&rsquo;\u00e9tonnante ville de Saint-Jacques-de-Compostelle, la capitale galicienne.<\/strong><\/h6><\/div><style>.ld_fancy_heading_6a0464664a6b6 p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a0464664a6b6 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a0464664a6b6 p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a0464664a6b6\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <em><strong>La ville historique<\/strong><\/em> : Pour commencer la journ\u00e9e, rien de tel qu&rsquo;une jolie balade dans les rues et places de la vieille ville. Un d\u00e9dale de rues \u00e9troites, de places et de b\u00e2timents en granit, fier de ses si\u00e8cles d&rsquo;histoire et remontant \u00e0 l&rsquo;\u00e9poque m\u00e9di\u00e9vale.<br \/>\nParmi eux, ne manquez pas la majestueuse cath\u00e9drale de la place Obradoiro que des milliers de visiteurs et de p\u00e8lerins se pressent pour admirer. Apr\u00e8s la visite matinale de ce joyau architectural, les visiteurs peuvent assister \u00e0 la messe qui a lieu \u00e0 midi. Pendant la c\u00e9l\u00e9bration, le botafumeiro \u2013 un gigantesque encensoir \u2013 survole le temple et ce rituel est d\u00e9finitivement une exp\u00e9rience m\u00e9morable. C&rsquo;est peut-\u00eatre l&rsquo;occasion r\u00eav\u00e9e de grimper sur les toits de la cath\u00e9drale et d&rsquo;admirer la ville depuis son point culminant.<br \/>\nPour reprendre des forces avant de poursuivre la visite, faites une pause dans l&rsquo;un des bars ou restaurants qui vous permettent de d\u00e9couvrir la cuisine galicienne, et laissez-vous rassasi\u00e9 et conquis par ces saveurs.<\/p>\n<p><em><strong>Aller-retour culturel<\/strong><\/em> : L&rsquo;apr\u00e8s-midi, profitez et admirez les parcs et jardins de Saint-Jacques-de-Compostelle, dont le parc Alameda, \u00e0 proximit\u00e9 du centre historique. Cet espace, cr\u00e9\u00e9 au XIXe si\u00e8cle, offre encore aujourd&rsquo;hui un point de vue privil\u00e9gi\u00e9 sur la vieille ville.<br \/>\nEnsuite, vous pouvez revenir au centre, mais en changeant d&rsquo;itin\u00e9raire pour passer devant la Facult\u00e9 d&rsquo;Histoire et de G\u00e9ographie, l&rsquo;\u00e9glise San Fiz de solivi et le march\u00e9 de gros.<br \/>\nLa visite se poursuit au parc Bonaval pour visiter deux mus\u00e9es importants, le Mus\u00e9e galicien d&rsquo;art contemporain et le Mus\u00e9e du peuple galicien. En chemin, vous pourrez voir le couvent de San Agust\u00edn, l&rsquo;\u00e9glise de Santa Mar\u00eda del Camino et la Puerta del Camino.<\/p>\n<p><em><strong>Cath\u00e9drale de nuit<\/strong><\/em> : Apr\u00e8s avoir visit\u00e9 les principaux mus\u00e9es de la ville, nous retournons \u00e0 la cath\u00e9drale qui est illumin\u00e9e la nuit. Pour ce faire, les visiteurs passeront sous la Puerta del Camino, se rendront \u00e0 la Plaza Cervantes, remonteront la rue de l&rsquo;Azabacher\u00eda et arriveront rapidement \u00e0 San Mart\u00edn Pinario.<br \/>\nPendant une demi-heure, les visiteurs auront l&rsquo;occasion d&rsquo;admirer la Plaza del Obradoiro et les monuments qui l&rsquo;entourent, tous illumin\u00e9s : la cath\u00e9drale, le Parador de los Reyes Catolicos, le palais Rajoy et le Coll\u00e8ge de San Jer\u00f3nimo.<br \/>\nCe moment magique peut avoir lieu \u00e0 la demande du client, avant ou apr\u00e8s le d\u00eener, o\u00f9 les visiteurs ont la possibilit\u00e9 de d\u00e9guster une bonne assiette de fruits de mer, de poisson ou de riz galicien.<br \/>\nApr\u00e8s le d\u00eener et la visite, pourquoi ne pas prendre un verre en \u00e9coutant de la musique ?<br \/>\nDans le centre historique, plusieurs bars et pubs offrent un d\u00e9cor et une ambiance.<\/p><\/div><\/div><div id=\"lqd-1682099693389-70fd6c87-9e9a\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a0464664a9b0 h5{color:#6ebb1f;}.ld_fancy_heading_6a0464664a9b0 h5 {font-size:25px; } .ld_fancy_heading_6a0464664a9b0 h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a0464664a9b0 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a0464664a9b0 h5 {font-size:25px; } .ld_fancy_heading_6a0464664a9b0 h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a0464664a9b0\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Visite \u00e0 v\u00e9lo<\/h5><\/div><style>.ld_content_box_6a0464664abad .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a0464664abad\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a0464664abad\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 700 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/shutterstock_69459250.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/shutterstock_69459250.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/shutterstock_69459250-300x129.jpeg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" data-aspect=\"2.3333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t<i class=\"fas fa-bicycle\"><\/i>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 Saint-Jacques-de-Compostelle<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Visite \u00e0 v\u00e9lo<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a0464664cc82{height:30px;}@media (min-width: 992px) { .ld_spacer_6a0464664cc82{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a0464664cc82\"><\/div><style>.ld_fancy_heading_6a0464664ce2c h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a0464664ce2c .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a0464664ce2c h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a0464664ce2c\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <strong>Saint-Jacques-de-Compostelle est une ville parfaite pour une balade \u00e0 v\u00e9lo ! Nous vous proposons de participer \u00e0 une visite guid\u00e9e \u00e0 v\u00e9lo comme moyen actif et divertissant de conna\u00eetre l\u2019histoire de la ville et le charme de la vieille ville m\u00e9di\u00e9vale.<\/strong><\/h6><\/div><style>.ld_fancy_heading_6a0464664d046 p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a0464664d046 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a0464664d046 p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a0464664d046\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Depuis Saint-Jacques-de-Compostelle, vous pouvez vous aventurer dans la direction oppos\u00e9e, sur le chemin de Saint-Jacques qu&#8217;empruntent les p\u00e8lerins jusqu&rsquo;\u00e0 la cath\u00e9drale. Vous d\u00e9couvrirez l&rsquo;ambiance et l&rsquo;\u00e9motion qui se d\u00e9gagent de ce parcours et vous reviendrez apais\u00e9 au centre de la ville.<\/p>\n<p>Pour se rafra\u00eechir, il est possible de pr\u00e9voir une halte dans un bar pour d\u00e9jeuner et d\u00e9guster quelques tapas comme les moules galiciennes, les poivrons de Padron, l&rsquo;\u00e9picerie fine locale, d\u00e9couvrir la \u00ab Mariscada \u00bb &#8211; un plat compos\u00e9 presque exclusivement de fruits de mer, de homards, de crabes et d&rsquo;autres crustac\u00e9s &#8211; mais aussi la \u00ab tarta de Santiago \u00bb. Le tout \u00e0 d\u00e9guster avec une bi\u00e8re bien fra\u00eeche, l&rsquo;Estrella Galicia &#8211; une bi\u00e8re blonde symbole de la r\u00e9gion -.<\/p>\n<p>Nous souhaitons que vous divertissiez vos papilles gustatives avec l&rsquo;aide de produits locaux exquis du pays galicien.<\/p><\/div><\/div><div id=\"lqd-1682100880311-e775a2c7-a375\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a0464664d2da h5{color:#6ebb1f;}.ld_fancy_heading_6a0464664d2da h5 {font-size:25px; } .ld_fancy_heading_6a0464664d2da h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a0464664d2da .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a0464664d2da h5 {font-size:25px; } .ld_fancy_heading_6a0464664d2da h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a0464664d2da\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Activit\u00e9s sportives<\/h5><\/div><style>.ld_content_box_6a0464664d4b0 .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a0464664d4b0\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a0464664d4b0\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 700 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/shutterstock_123768817.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/shutterstock_123768817.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/shutterstock_123768817-300x129.jpeg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" data-aspect=\"2.3333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 Saint-Jacques-de-Compostelle<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Activit\u00e9s sportives<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a0464664f657{height:30px;}@media (min-width: 992px) { .ld_spacer_6a0464664f657{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a0464664f657\"><\/div><style>.ld_fancy_heading_6a0464664f7f2 h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a0464664f7f2 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a0464664f7f2 h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a0464664f7f2\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <\/p>\n<div id=\"intro\">\n<p><strong>Santiago de Compostela is an ideal place to enjoy the surrounding nature and many sports.<\/strong><\/p>\n<\/div>\n<p><\/h6><\/div><style>.ld_fancy_heading_6a0464664fa44 p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a0464664fa44 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a0464664fa44 p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a0464664fa44\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Aux alentours de Saint-Jacques-de-Compostelle, les vall\u00e9es et les for\u00eats \u00e0 la v\u00e9g\u00e9tation luxuriante sont des sites id\u00e9aux pour la pratique de randonn\u00e9es et autres sports. Si vous aimez le sport, Saint-Jacques-de-Compostelle est une destination id\u00e9ale pour les sports d&rsquo;aventure, mais aussi pour les parcours de golf.<\/p>\n<p>A seulement une demi-heure en voiture ou en bus, vous trouverez des plages et des points d&rsquo;eau d&rsquo;un grand int\u00e9r\u00eat \u00e9cologique. Le cano\u00eb, l&rsquo;hydrorafting et le kite surf se pratiquent sur les parcours de l&rsquo;Ulla, du Mino, du Tambre et \u00e9galement dans les eaux de Baixas et Rias Altas. Pour les activit\u00e9s de plong\u00e9e, vous pourrez vous initier sur la c\u00f4te galicienne, quel que soit votre niveau.<\/p>\n<p>Pour les plus patients et les plus calmes d&rsquo;entre vous, les rivi\u00e8res et \u00e9tangs de la r\u00e9gion constituent un terrain de jeu id\u00e9al pour la p\u00eache \u00e0 la truite ou au saumon.<\/p>\n<p>Enyevent DMC trouvera l&rsquo;activit\u00e9 la plus adapt\u00e9e \u00e0 votre projet en fonction de votre objectif.<\/p><\/div><\/div><div id=\"lqd-1682100543635-94960ecb-75f1\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a0464664fcb5 h5{color:#6ebb1f;}.ld_fancy_heading_6a0464664fcb5 h5 {font-size:25px; } .ld_fancy_heading_6a0464664fcb5 h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a0464664fcb5 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a0464664fcb5 h5 {font-size:25px; } .ld_fancy_heading_6a0464664fcb5 h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a0464664fcb5\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Classes de cuisine<\/h5><\/div><style>.ld_content_box_6a0464664feb4 .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a0464664feb4\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a0464664feb4\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 700 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/Enyevent_cooking_canary.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/Enyevent_cooking_canary.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/Enyevent_cooking_canary-300x129.jpeg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" data-aspect=\"2.3333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t<i class=\"fas fa-utensils\"><\/i>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 Saint-Jacques-de-Compostelle<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Classes de cuisine<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a04646651f96{height:30px;}@media (min-width: 992px) { .ld_spacer_6a04646651f96{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a04646651f96\"><\/div><style>.ld_fancy_heading_6a04646652156 h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a04646652156 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a04646652156 h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a04646652156\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <strong>D\u00e9couvrez les secrets de la cuisine galicienne authentique et traditionnelle et travaillez avec les membres de votre \u00e9quipe pour pr\u00e9parer un d\u00e9licieux repas lors d&rsquo;un cours de cuisine.<\/strong><\/h6><\/div><style>.ld_fancy_heading_6a04646652368 p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a04646652368 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a04646652368 p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a04646652368\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Il n&rsquo;y a pas de meilleur moyen de p\u00e9n\u00e9trer au c\u0153ur d&rsquo;une ville ou d&rsquo;une r\u00e9gion qu&rsquo;en apprenant \u00e0 cr\u00e9er sa sp\u00e9cialit\u00e9 locale, comme la Mariscada \u00e0 Saint-Jacques-de-Compostelle, et en profitant de l&rsquo;ambiance conviviale et d\u00e9tendue du cours qui permet aux membres de l&rsquo;\u00e9quipe de travailler ensemble. dans cette activit\u00e9 pratique, partageant des t\u00e2ches et apprenant de nouvelles m\u00e9thodes de cuisine.<\/p>\n<p>Les cours sont con\u00e7us pour tous les niveaux de difficult\u00e9 et il y en a pour tous les go\u00fbts, du d\u00e9butant au cuisinier plus exp\u00e9riment\u00e9.<\/p>\n<p>Les cours de cuisine commenceront par une visite du march\u00e9 local o\u00f9 des produits frais locaux pourront \u00eatre achet\u00e9s pour \u00eatre utilis\u00e9s comme ingr\u00e9dients pendant le cours et des conseils d&rsquo;un guide expert seront donn\u00e9s tout au long du parcours sur la fa\u00e7on de s\u00e9lectionner les meilleurs produits de saison.<\/p>\n<p>Dans les cuisines bien \u00e9quip\u00e9es, les merveilleux parfums des plats d\u00e9licieux ouvriront l&rsquo;app\u00e9tit afin qu&rsquo;une fois tout le travail termin\u00e9, les r\u00e9sultats du travail soient pr\u00e9sent\u00e9s \u00e0 l&rsquo;\u00e9quipe pour qu&rsquo;ils puissent les d\u00e9guster avec un bon verre de vin galicien ou une bi\u00e8re. !<\/p><\/div><\/div><div id=\"lqd-1682098856421-82b74996-23ce\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a04646652603 h5{color:#6ebb1f;}.ld_fancy_heading_6a04646652603 h5 {font-size:25px; } .ld_fancy_heading_6a04646652603 h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a04646652603 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a04646652603 h5 {font-size:25px; } .ld_fancy_heading_6a04646652603 h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a04646652603\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Santiago \u00e0 cheval<\/h5><\/div><style>.ld_content_box_6a046466527da .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a046466527da\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a046466527da\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 700 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/rando-horseback.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/rando-horseback.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/rando-horseback-300x129.jpeg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" data-aspect=\"2.3333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t<i class=\"fas fa-horse\"><\/i>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 Saint-Jacques-de-Compostelle<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Santiago \u00e0 cheval<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a046466548ba{height:30px;}@media (min-width: 992px) { .ld_spacer_6a046466548ba{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a046466548ba\"><\/div><style>.ld_fancy_heading_6a04646654a51 h6 {margin-bottom:1em !important;  } .ld_fancy_heading_6a04646654a51 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a04646654a51 h6 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a04646654a51\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <strong>Dans la cit\u00e9 m\u00e9di\u00e9vale de Saint Jacques de Compostelle, Enyevent DMC vous invite pour une activit\u00e9 \u00e9pique.<\/strong><\/h6><\/div><style>.ld_fancy_heading_6a04646654c82 p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a04646654c82 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a04646654c82 p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a04646654c82\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Apr\u00e8s une visite p\u00e9destre dans le centre de Saint-Jacques-de-Compostelle, les participants se rendent dans un centre \u00e9questre pour une activit\u00e9 ludique et passionnante.<\/p>\n<p>A son arriv\u00e9e, chaque participant se voit attribuer un cheval adapt\u00e9 \u00e0 son niveau et \u00e0 sa taille et est arm\u00e9 de son \u00e9quipement de s\u00e9curit\u00e9. C\u2019est alors que les superviseurs expliquent les consignes \u00e0 suivre. La le\u00e7on se poursuit par une conduite lente afin que les \u00e9quipiers puissent s&rsquo;habituer et faire confiance \u00e0 leurs chevaux.<\/p>\n<p>Vient ensuite la promenade sur le Camino de Santiago. Les participants sont encadr\u00e9s par des moniteurs et suivent le parcours indiqu\u00e9. Durant la balade, les courageux pourront s&rsquo;aventurer, toujours accompagn\u00e9s d&rsquo;un encadrant pour effectuer une course au trot ou au galop pour les plus exp\u00e9riment\u00e9s.<\/p>\n<p>Apr\u00e8s la balade, et pour plus de comp\u00e9tition, Enyevent DMC peut organiser un petit quiz historique sur la visite matinale avec des cadeaux, et recueillir les retours des participants sur l&rsquo;activit\u00e9 de l&rsquo;apr\u00e8s-midi autour d&rsquo;un verre dans l&rsquo;un des bars du centre-ville.<\/p><\/div><\/div><div id=\"lqd-1682101131837-cc7a49bc-07e6\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a04646654ef9 h5{color:#6ebb1f;}.ld_fancy_heading_6a04646654ef9 h5 {font-size:25px; } .ld_fancy_heading_6a04646654ef9 h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a04646654ef9 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a04646654ef9 h5 {font-size:25px; } .ld_fancy_heading_6a04646654ef9 h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a04646654ef9\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Excursions<\/h5><\/div><style>.ld_content_box_6a046466550f4 .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a046466550f4\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a046466550f4\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 700 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/coruna-spain.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/coruna-spain.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/coruna-spain-300x129.jpeg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" data-aspect=\"2.3333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 Saint-Jacques-de-Compostelle<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Excursions<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a04646657161{height:30px;}@media (min-width: 992px) { .ld_spacer_6a04646657161{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a04646657161\"><\/div><style>.ld_fancy_heading_6a04646657328 h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a04646657328 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a04646657328 h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a04646657328\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <strong>Apr\u00e8s avoir visit\u00e9 Saint-Jacques de Compostelle, Enyevent DMC propose aux participants d&rsquo;explorer d&rsquo;autres villes de la r\u00e9gion galicienne, riches en histoire, en connaisseurs de fine gastronomie et de paysages extraordinaires&#8230;<\/strong><\/h6><\/div><style>.ld_fancy_heading_6a0464665753d p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a0464665753d .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a0464665753d p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a0464665753d\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <em><strong>La Corogne<\/strong><\/em> : Situ\u00e9e au bord de l&rsquo;oc\u00e9an Atlantique, La Corogne est une ville historique dont l&rsquo;histoire a entretenu des liens \u00e9troits avec son ancien port de p\u00eache et de commerce. La p\u00e9ninsule sur laquelle se dresse la Vieille Ville abrite \u00e9galement la Tour d&rsquo;Hercule, l&rsquo;un des symboles de la ville, qui constitue un int\u00e9ressant ensemble roman de rues, de places et d&rsquo;\u00e9glises m\u00e9di\u00e9vales. Les membres de l&rsquo;\u00e9quipe peuvent commencer la visite en suivant la nouvelle promenade le long de le littoral, qui est l&rsquo;un des plus longs d&rsquo;Europe, et qui vous m\u00e8nera aux plages Playa del Orzan et Playa Riazor. Vous pouvez vous arr\u00eater \u00e0 Playa del Orzan pour visiter le mus\u00e9e Domus ou la Casa del Hombre, un mus\u00e9e qui combine l&rsquo;anthropologie, l&rsquo;histoire naturelle et les sciences, ainsi que d&rsquo;int\u00e9ressantes expositions interactives.<br \/>\nPour continuer la visite, votre groupe ne peut pas manquer le ch\u00e2teau de San Ant\u00f3n, une forteresse datant du XVIe si\u00e8cle, situ\u00e9e sur une petite \u00eele et reli\u00e9e artificiellement au continent ; le Castillo de San Diego, qui abrite le mus\u00e9e arch\u00e9ologique de La Corogne et situ\u00e9 de l&rsquo;autre c\u00f4t\u00e9 de la baie ; la Casa de los Peces, un aquarium avec plus de 300 esp\u00e8ces et les belles \u00e9glises.Rias altas (excursion en bateau)<\/p>\n<p><em><strong>Rias Baixas<\/strong><\/em> : Au sud-ouest de la Galice, depuis le Monte Louro de Muros jusqu&rsquo;\u00e0 l&#8217;embouchure du fleuve Mi\u00f1o, les R\u00edas Baixas affichent la couleur d&rsquo;une mer qui p\u00e9n\u00e8tre dans la terre. Les paysages sont charg\u00e9s d&rsquo;histoire et les petits villages de p\u00eacheurs tr\u00e8s accueillants pour profiter de votre voyage \u00e0 tout moment de l&rsquo;ann\u00e9e.<br \/>\nDans la matin\u00e9e, vous quitterez l&rsquo;h\u00f4tel avec votre autocar priv\u00e9 en direction de Padr\u00f3n, o\u00f9 nous visiterons Santiagui\u00f1o do Monte. Ensuite, la visite se poursuit \u00e0 Catoira, un village qui poss\u00e8de l&rsquo;une des forteresses d\u00e9fensives les plus imprenables de Galice, les Torres de Arzobispo, et \u00e0 Cambados, la capitale du vin blanc Albari\u00f1o de renomm\u00e9e mondiale. Vous pouvez \u00e9galement profiter d&rsquo;une promenade en bateau le long de la Ria.<br \/>\nUne excursion dans les R\u00edas Baixas est \u00e9galement le moment id\u00e9al pour d\u00e9guster la meilleure cuisine de Galice : de fines recettes \u00e0 base de poisson et de fruits de mer qui se d\u00e9gustent mieux accompagn\u00e9es d&rsquo;un vin typique de cette terre.<\/p><\/div><\/div><div id=\"lqd-1682101311230-40f07417-99ab\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a046466577e9 h5{color:#6ebb1f;}.ld_fancy_heading_6a046466577e9 h5 {font-size:25px; } .ld_fancy_heading_6a046466577e9 h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a046466577e9 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046466577e9 h5 {font-size:25px; } .ld_fancy_heading_6a046466577e9 h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046466577e9\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  D\u00e9gustation de vins<\/h5><\/div><style>.ld_content_box_6a046466579c0 .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a046466579c0\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a046466579c0\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"627\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 627 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/Enyevent_wine-rioja.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/Enyevent_wine-rioja.jpeg 627w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/05\/Enyevent_wine-rioja-300x144.jpeg 300w\" data-sizes=\"(max-width: 627px) 100vw, 627px\" data-aspect=\"2.09\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t<i class=\"fas fa-wine-glass-alt\"><\/i>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 Saint-Jacques-de-Compostelle<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">D\u00e9gustation de vins<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a04646659a9c{height:30px;}@media (min-width: 992px) { .ld_spacer_6a04646659a9c{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a04646659a9c\"><\/div><style>.ld_fancy_heading_6a04646659c30 h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a04646659c30 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a04646659c30 h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a04646659c30\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <strong>Ce programme parfait pour une excursion hors de Saint-Jacques-de-Compostelle, dans la province de Pontevedra, vous invite dans une cave qui pr\u00e9pare un albari\u00f1o pur produit selon un processus rigoureux et m\u00e9ticuleux afin de garantir sa puret\u00e9 vari\u00e9tale et l&rsquo;essence traditionnelle de la vall\u00e9e de Saln\u00e9s originale. vins.<\/strong><\/h6><\/div><style>.ld_fancy_heading_6a04646659e66 p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a04646659e66 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a04646659e66 p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a04646659e66\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Votre guide officiel vous expliquera l&rsquo;histoire de la r\u00e9gion pendant le voyage depuis Saint-Jacques-de-Compostelle qui prendra moins d&rsquo;une heure en bus priv\u00e9.<\/p>\n<p>A votre arriv\u00e9e, votre groupe pourra entrer dans la \u00ab bodega \u00bb. Vous aurez la chance, pendant une heure, de d\u00e9couvrir le domaine et son univers particulier gr\u00e2ce \u00e0 un guide qui vous expliquera le processus de vinification. Les participants suivront le personnel de la cave, qui leur expliquera l&rsquo;\u00e9laboration du vin et ses proc\u00e9d\u00e9s, suivi d&rsquo;une d\u00e9gustation de quatre vins anim\u00e9e par l&rsquo;\u0153nologue de la maison.<\/p>\n<p>Bien entendu, l&rsquo;ordre des activit\u00e9s peut \u00eatre modifi\u00e9 selon vos envies, et il est possible de r\u00e9server la salle du domaine viticole pour une conf\u00e9rence ou un quizz, suivi d&rsquo;un d\u00e9jeuner ou d&rsquo;un d\u00eener dans un restaurant typique avant de repartir vers Saint-Jacques-de-Compostelle.<\/p><\/div><\/div><\/div>\n<\/div>\n[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4925,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4871","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Santiago de Compostela - Enyevent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enyevent.com\/es\/destinos\/santiago-de-compostela\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Santiago de Compostela - Enyevent\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enyevent.com\/es\/destinos\/santiago-de-compostela\/\" \/>\n<meta property=\"og:site_name\" content=\"Enyevent\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Enyevent-Solutions\/1429727033923570\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-18T21:45:50+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EnyeventSL\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/enyevent.com\/es\/destinos\/santiago-de-compostela\/\",\"url\":\"https:\/\/enyevent.com\/es\/destinos\/santiago-de-compostela\/\",\"name\":\"Santiago de Compostela - Enyevent\",\"isPartOf\":{\"@id\":\"https:\/\/enyevent.com\/#website\"},\"datePublished\":\"2023-05-10T19:12:38+00:00\",\"dateModified\":\"2024-03-18T21:45:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/enyevent.com\/es\/destinos\/santiago-de-compostela\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/enyevent.com\/es\/destinos\/santiago-de-compostela\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/enyevent.com\/es\/destinos\/santiago-de-compostela\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/enyevent.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gestion des destinations\",\"item\":\"https:\/\/enyevent.com\/es\/destinos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Santiago de Compostela\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/enyevent.com\/#website\",\"url\":\"https:\/\/enyevent.com\/\",\"name\":\"Enyevent\",\"description\":\"DMC Spain and France - Event planner in Spain and France\",\"publisher\":{\"@id\":\"https:\/\/enyevent.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/enyevent.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/enyevent.com\/#organization\",\"name\":\"Enyevent\",\"url\":\"https:\/\/enyevent.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/enyevent.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/logo-enyevent.png\",\"contentUrl\":\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/logo-enyevent.png\",\"width\":226,\"height\":71,\"caption\":\"Enyevent\"},\"image\":{\"@id\":\"https:\/\/enyevent.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pages\/Enyevent-Solutions\/1429727033923570\",\"https:\/\/x.com\/EnyeventSL\",\"https:\/\/www.instagram.com\/enyeventspaindmc\",\"http:\/\/www.youtube.com\/channel\/UCDehJbTpYupuXUgSye4jxjA\/about\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Santiago de Compostela - Enyevent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enyevent.com\/es\/destinos\/santiago-de-compostela\/","og_locale":"fr_FR","og_type":"article","og_title":"Santiago de Compostela - Enyevent","og_description":"[vc_row][vc_column][\/vc_column][\/vc_row]","og_url":"https:\/\/enyevent.com\/es\/destinos\/santiago-de-compostela\/","og_site_name":"Enyevent","article_publisher":"https:\/\/www.facebook.com\/pages\/Enyevent-Solutions\/1429727033923570","article_modified_time":"2024-03-18T21:45:50+00:00","twitter_card":"summary_large_image","twitter_site":"@EnyeventSL","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"16 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/enyevent.com\/es\/destinos\/santiago-de-compostela\/","url":"https:\/\/enyevent.com\/es\/destinos\/santiago-de-compostela\/","name":"Santiago de Compostela - Enyevent","isPartOf":{"@id":"https:\/\/enyevent.com\/#website"},"datePublished":"2023-05-10T19:12:38+00:00","dateModified":"2024-03-18T21:45:50+00:00","breadcrumb":{"@id":"https:\/\/enyevent.com\/es\/destinos\/santiago-de-compostela\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enyevent.com\/es\/destinos\/santiago-de-compostela\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/enyevent.com\/es\/destinos\/santiago-de-compostela\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/enyevent.com\/es\/"},{"@type":"ListItem","position":2,"name":"Gestion des destinations","item":"https:\/\/enyevent.com\/es\/destinos\/"},{"@type":"ListItem","position":3,"name":"Santiago de Compostela"}]},{"@type":"WebSite","@id":"https:\/\/enyevent.com\/#website","url":"https:\/\/enyevent.com\/","name":"Enyevent","description":"DMC Spain and France - Event planner in Spain and France","publisher":{"@id":"https:\/\/enyevent.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enyevent.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/enyevent.com\/#organization","name":"Enyevent","url":"https:\/\/enyevent.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/enyevent.com\/#\/schema\/logo\/image\/","url":"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/logo-enyevent.png","contentUrl":"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/logo-enyevent.png","width":226,"height":71,"caption":"Enyevent"},"image":{"@id":"https:\/\/enyevent.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Enyevent-Solutions\/1429727033923570","https:\/\/x.com\/EnyeventSL","https:\/\/www.instagram.com\/enyeventspaindmc","http:\/\/www.youtube.com\/channel\/UCDehJbTpYupuXUgSye4jxjA\/about"]}]}},"_links":{"self":[{"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/pages\/4871"}],"collection":[{"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/comments?post=4871"}],"version-history":[{"count":5,"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/pages\/4871\/revisions"}],"predecessor-version":[{"id":5683,"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/pages\/4871\/revisions\/5683"}],"up":[{"embeddable":true,"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/pages\/4925"}],"wp:attachment":[{"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/media?parent=4871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}