{"id":4877,"date":"2023-04-22T20:16:36","date_gmt":"2023-04-22T20:16:36","guid":{"rendered":"https:\/\/enyevent.com\/index.php\/seville\/"},"modified":"2024-03-19T19:44:15","modified_gmt":"2024-03-19T19:44:15","slug":"seville","status":"publish","type":"page","link":"https:\/\/enyevent.com\/fr\/destinations\/seville\/","title":{"rendered":"Seville"},"content":{"rendered":"<p>[vc_row][vc_column]<style>.ld_spacer_6a046329bb229{height:32px;}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a046329bb229\"><\/div><style><\/style><div class=\"lqd-tabs lqd-tabs-style-6 d-flex flex-wrap ld_tabs_6a046329e09dd\" data-tabs-options='{\"trigger\":\"click\"}'>\n\n\t<nav class=\"lqd-tabs-nav-wrap\">\n\t\t<ul class=\"reset-ul lqd-tabs-nav d-flex flex-column \" role=\"tablist\"><li data-controls=\"lqd-1682073809060-587281a8-c4b4\" role=\"presentation\" class=\"ld_tab_section-6a046329bb47e active font-weight-medium\"><a class=\"py-3 round\" href=\"#lqd-1682073809060-587281a8-c4b4\" aria-expanded=\"false\" aria-controls=\"lqd-1682073809060-587281a8-c4b4\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Seville<\/span><\/a><\/li><li data-controls=\"lqd-1680778113079-572ae9e5-5561\" role=\"presentation\" class=\"ld_tab_section-6a046329bc111 font-weight-medium\"><a class=\"py-3 round\" href=\"#lqd-1680778113079-572ae9e5-5561\" aria-expanded=\"false\" aria-controls=\"lqd-1680778113079-572ae9e5-5561\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Visite \u00e0 v\u00e9lo<\/span><\/a><\/li><li data-controls=\"lqd-1682099693389-70fd6c87-9e9a\" role=\"presentation\" class=\"ld_tab_section-6a046329bf1a1 font-weight-medium\"><a class=\"py-3 round\" href=\"#lqd-1682099693389-70fd6c87-9e9a\" aria-expanded=\"false\" aria-controls=\"lqd-1682099693389-70fd6c87-9e9a\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Jeu de la ville<\/span><\/a><\/li><li data-controls=\"lqd-1682100543635-94960ecb-75f1\" role=\"presentation\" class=\"ld_tab_section-6a046329c358a font-weight-medium\"><a class=\"py-3 round\" href=\"#lqd-1682100543635-94960ecb-75f1\" aria-expanded=\"false\" aria-controls=\"lqd-1682100543635-94960ecb-75f1\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Atelier de flamenco<\/span><\/a><\/li><li data-controls=\"lqd-1682100880311-e775a2c7-a375\" role=\"presentation\" class=\"ld_tab_section-6a046329c6eb8 font-weight-medium\"><a class=\"py-3 round\" href=\"#lqd-1682100880311-e775a2c7-a375\" aria-expanded=\"false\" aria-controls=\"lqd-1682100880311-e775a2c7-a375\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Faire du ballon ascensionnel<\/span><\/a><\/li><li data-controls=\"lqd-1682098856421-82b74996-23ce\" role=\"presentation\" class=\"ld_tab_section-6a046329c9b0c font-weight-medium\"><a class=\"py-3 round\" href=\"#lqd-1682098856421-82b74996-23ce\" aria-expanded=\"false\" aria-controls=\"lqd-1682098856421-82b74996-23ce\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Grand Prix Moto de Jerez<\/span><\/a><\/li><li data-controls=\"lqd-1682101913122-39af1888-036a\" role=\"presentation\" class=\"ld_tab_section-6a046329d5513 font-weight-medium\"><a class=\"py-3 round\" href=\"#lqd-1682101913122-39af1888-036a\" aria-expanded=\"false\" aria-controls=\"lqd-1682101913122-39af1888-036a\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Visite en Segway<\/span><\/a><\/li><li data-controls=\"lqd-1682101131837-cc7a49bc-07e6\" role=\"presentation\" class=\"ld_tab_section-6a046329d8236 font-weight-medium\"><a class=\"py-3 round\" href=\"#lqd-1682101131837-cc7a49bc-07e6\" aria-expanded=\"false\" aria-controls=\"lqd-1682101131837-cc7a49bc-07e6\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Visites et excursions<\/span><\/a><\/li><li data-controls=\"lqd-1682101311230-40f07417-99ab\" role=\"presentation\" class=\"ld_tab_section-6a046329db19c font-weight-medium\"><a class=\"py-3 round\" href=\"#lqd-1682101311230-40f07417-99ab\" aria-expanded=\"false\" aria-controls=\"lqd-1682101311230-40f07417-99ab\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Tapas sautillantes<\/span><\/a><\/li><li data-controls=\"lqd-1682195028895-7c3f8ae9-d48c\" role=\"presentation\" class=\"ld_tab_section-6a046329dddcc font-weight-medium\"><a class=\"py-3 round\" href=\"#lqd-1682195028895-7c3f8ae9-d48c\" aria-expanded=\"false\" aria-controls=\"lqd-1682195028895-7c3f8ae9-d48c\" role=\"tab\" data-toggle=\"tab\"><span class=\"lqd-tabs-nav-txt\">Rallye 4x4 dans la Sierra Norte<\/span><\/a><\/li><\/ul>\t\t \n\t<\/nav>\n\n\t<div class=\"lqd-tabs-content pl-sm-5 pt-5 pt-sm-0\"><div id=\"lqd-1682073809060-587281a8-c4b4\" role=\"tabpanel\" class=\"lqd-tabs-pane fade active in\"><style>.ld_fancy_heading_6a046329bb55e h5{color:#6ebb1f;}.ld_fancy_heading_6a046329bb55e h5 {font-size:25px; } .ld_fancy_heading_6a046329bb55e h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a046329bb55e .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329bb55e h5 {font-size:25px; } .ld_fancy_heading_6a046329bb55e h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329bb55e\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Seville<\/h5><\/div><style>.ld_content_box_6a046329bb826 .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a046329bb826\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a046329bb826\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"299\" src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_seville_destination.jpeg\" class=\"w-100 invisible\" alt=\"\" srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_seville_destination.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_seville_destination-300x128.jpeg 300w\" sizes=\"(max-width: 700px) 100vw, 700px\" itemprop=\"image\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 S\u00e9ville<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Seville<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a046329bbbc1{height:30px;}@media (min-width: 992px) { .ld_spacer_6a046329bbbc1{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a046329bbbc1\"><\/div><style>.ld_fancy_heading_6a046329bbd37 h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329bbd37 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329bbd37 h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329bbd37\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <strong>S\u00e9ville respire la romance, avec ses ruelles pav\u00e9es sinueuses reliant de belles places et se faufilant \u00e0 travers une grande vari\u00e9t\u00e9 d&rsquo;architecture, bord\u00e9es de bougainvilliers roses et d&rsquo;orangers en fleurs. Son histoire mouvement\u00e9e lui a donn\u00e9 de nombreuses saveurs diff\u00e9rentes, avec des influences romaines, maures et chr\u00e9tiennes, entre autres, qui font que chaque d\u00e9tour est plein d&rsquo;anticipation et d&rsquo;attente.<\/strong><\/h6><\/div><style>.ld_fancy_heading_6a046329bbf32 p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329bbf32 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329bbf32 p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329bbf32\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  En tant que capitale de l&rsquo;Andalousie et quatri\u00e8me plus grande ville d&rsquo;Espagne, elle est tout sauf petite, mais la vieille ville compacte donne l&rsquo;impression que tout est \u00e0 port\u00e9e de main. Elle parvient \u00e0 capturer l&rsquo;atmosph\u00e8re d&rsquo;une petite ville, tout en regorgeant d&rsquo;une architecture accrocheuse, d&rsquo;ic\u00f4nes mondialement reconnues et d&rsquo;un creuset de cultures. La cath\u00e9drale de la ville est la plus grande cath\u00e9drale gothique du monde et m\u00e9rite d&rsquo;\u00eatre \u00e9merveill\u00e9e, tout comme l&rsquo;Alcazar, qui a accueilli de nombreux dirigeants de la ville au cours de son histoire. Ensuite, il y a la Plaza de Espa\u00f1a, un site unique et \u00e9poustouflant qui semble surnaturel, comme cela a \u00e9t\u00e9 prouv\u00e9 lorsqu&rsquo;il a \u00e9t\u00e9 choisi pour figurer dans les films Star Wars.<\/p>\n<p>Au-del\u00e0 de ses b\u00e2timents et de ses jardins, S\u00e9ville abrite \u00e9galement deux des principales traditions andalouses\u00a0: flamenco et combats de taureaux. Les S\u00e9villans affluent vers les ar\u00e8nes en saison pour juger du machisme des matadors pr\u00e9sents, et le flamenco est incontournable, qu&rsquo;il s&rsquo;agisse d&rsquo;un spectacle impromptu dans un bar d&rsquo;une rue ou des stands de billets pour les spectacles touristiques qui bordent la vieille ville. Ces deux traditions regorgent de passion, et cette passion ne manque pas non plus ailleurs dans la ville.<\/p>\n<p>Compte tenu de sa taille et de son importance en Andalousie, ainsi que de son influence dans l&rsquo;ensemble de l&rsquo;Espagne, S\u00e9ville est un choix populaire pour les expositions, conf\u00e9rences et autres \u00e9v\u00e9nements d&rsquo;entreprise. Il a accueilli d&rsquo;\u00e9normes \u00e9v\u00e9nements dans le pass\u00e9, comme l&rsquo;Expo 92, et est plus que capable d&rsquo;accueillir des \u00e9v\u00e9nements de toutes formes et de toutes tailles. Avec son excellente infrastructure, la ville est tr\u00e8s facile \u00e0 visiter avec l&rsquo;a\u00e9roport, les trains \u00e0 grande vitesse, les autoroutes et m\u00eame un port fluvial vous permettant d&rsquo;arriver selon le style que vous pr\u00e9f\u00e9rez. \u00c0 l&rsquo;arriv\u00e9e, il est \u00e9galement extr\u00eamement facile de s&rsquo;y retrouver gr\u00e2ce \u00e0 un syst\u00e8me de tramway qui traverse la ville et de nombreuses zones pi\u00e9tonnes et clairement signal\u00e9es.<\/p>\n<p>Vous ne manquerez pas non plus d&rsquo;options en mati\u00e8re de loisirs, avec de nombreux sports de plein air, terrains de golf et autres activit\u00e9s pour vous occuper une fois que vous aurez explor\u00e9 tout ce que la ville a \u00e0 offrir.<\/p>\n<p>Gr\u00e2ce \u00e0 la combinaison d&rsquo;installations qu&rsquo;elle offre et au plaisir garanti en dehors des heures d&rsquo;ouverture, S\u00e9ville est une destination id\u00e9ale pour un \u00e9v\u00e9nement d&rsquo;affaires ou une escapade.<\/p><\/div><\/div><div id=\"lqd-1680778113079-572ae9e5-5561\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a046329bc1e5 h5{color:#6ebb1f;}.ld_fancy_heading_6a046329bc1e5 h5 {font-size:25px; } .ld_fancy_heading_6a046329bc1e5 h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a046329bc1e5 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329bc1e5 h5 {font-size:25px; } .ld_fancy_heading_6a046329bc1e5 h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329bc1e5\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Visite \u00e0 v\u00e9lo<\/h5><\/div><style>.ld_content_box_6a046329bc3bb .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a046329bc3bb\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a046329bc3bb\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 700 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_bike_sevilla.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_bike_sevilla.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_bike_sevilla-300x129.jpeg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" data-aspect=\"2.3333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t<i class=\"fas fa-bicycle\"><\/i>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 S\u00e9ville<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Visite \u00e0 v\u00e9lo<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a046329be89c{height:30px;}@media (min-width: 992px) { .ld_spacer_6a046329be89c{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a046329be89c\"><\/div><style>.ld_fancy_heading_6a046329beb37 h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329beb37 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329beb37 h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329beb37\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <strong>Comme c&rsquo;est le cas d&rsquo;autres grandes villes historiques d&rsquo;Espagne, S\u00e9ville est \u00e9galement une ville favorable aux cyclistes gr\u00e2ce aux r\u00e9cents plans d&rsquo;am\u00e9lioration du tourisme et \u00e0 l&rsquo;inauguration de pistes cyclables.<\/strong><\/h6><\/div><style>.ld_fancy_heading_6a046329beeec p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329beeec .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329beeec p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329beeec\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Cette activit\u00e9 vise \u00e0 offrir l&rsquo;opportunit\u00e9 de visiter les principales attractions de cette ville belle et magique dans un esprit d&rsquo;amusement et de divertissement, en d\u00e9couvrant \u00e9galement les sites qui ne figurent dans aucune brochure de voyage et guid\u00e9s par nos experts professionnels. Ce tour \u00e0 v\u00e9lo vous aidera \u00e0 vous orienter et vous fournira de nombreux conseils utiles pour votre temps libre pendant votre s\u00e9jour \u00e0 S\u00e9ville.<br \/>\nNous accompagnerons les participants de leur h\u00f4tel jusqu&rsquo;au magasin de v\u00e9los \u00e0 pied ou en bus priv\u00e9 selon la situation de l&rsquo;h\u00f4tel. Nos propres guides locaux multilingues viendront et vous donneront les premi\u00e8res indications.<\/p>\n<p>Nous pouvons organiser une visite sp\u00e9ciale visitant les lieux incontournables comme la Tour Dor\u00e9e ; la cath\u00e9drale d\u00e9clar\u00e9e site du patrimoine mondial de l&rsquo;UNESCO ; la Giralda, le monument le plus repr\u00e9sentatif de la ville et le palais fortifi\u00e9 de l&rsquo;Alcazar&#8230; Nous vous proposons de vous arr\u00eater prendre un verre et quelques tapas sur l&rsquo;une des terrasses ou de profiter d&rsquo;un pique-nique.<br \/>\nLa visite se poursuivra par la visite du c\u00e9l\u00e8bre quartier de Santa Cruz situ\u00e9 au centre-ville avec la beaut\u00e9 de ses maisons et palais blanchis \u00e0 la chaux et ses embl\u00e9matiques patios fleuris qui seront source d&rsquo;anecdotes \u00e0 raconter \u00e0 nos guides.<\/p>\n<p>Une fois la visite termin\u00e9e, en fonction de votre temps et de votre budget, nous serons heureux d&rsquo;organiser un agr\u00e9able d\u00e9jeuner o\u00f9 vous pourrez vous asseoir et vous d\u00e9tendre comme le font les autochtones, en d\u00e9gustant les plats typiques tels que le poisson frit, les crevettes fra\u00eeches, le jambon exquis. , accompagn\u00e9 de Manzanilla, de sherry et de Montilla ou bi\u00e8re dor\u00e9e.<br \/>\nIl est \u00e9galement possible d&rsquo;organiser des circuits \u00e0 v\u00e9lo adapt\u00e9s \u00e0 vos besoins particuliers : n&rsquo;importe quelle solution pour n&rsquo;importe quel \u00e9v\u00e9nement !<\/p><\/div><\/div><div id=\"lqd-1682099693389-70fd6c87-9e9a\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a046329bf345 h5{color:#6ebb1f;}.ld_fancy_heading_6a046329bf345 h5 {font-size:25px; } .ld_fancy_heading_6a046329bf345 h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a046329bf345 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329bf345 h5 {font-size:25px; } .ld_fancy_heading_6a046329bf345 h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329bf345\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Jeu de la ville<\/h5><\/div><style>.ld_content_box_6a046329bf678 .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a046329bf678\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a046329bf678\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 700 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_city_seville.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_city_seville.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_city_seville-300x129.jpeg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" data-aspect=\"2.3333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 S\u00e9ville<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Jeu de la ville<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a046329c2d30{height:30px;}@media (min-width: 992px) { .ld_spacer_6a046329c2d30{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a046329c2d30\"><\/div><style>.ld_fancy_heading_6a046329c2f9a h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329c2f9a .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329c2f9a h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329c2f9a\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <strong>Cette activit\u00e9 de groupe vous offre la possibilit\u00e9 de d\u00e9couvrir tous les beaux endroits de la ville tout en relevant diff\u00e9rents d\u00e9fis. L&rsquo;objectif principal est de conna\u00eetre S\u00e9ville d&rsquo;une mani\u00e8re diff\u00e9rente et agr\u00e9able. Mais les participants doivent \u00e9galement remplir d\u2019autres objectifs comme : travailler en \u00e9quipe, d\u00e9velopper leur imagination dans une saine comp\u00e9tition et \u2013 surtout \u2013 s\u2019amuser.<\/strong><\/h6><\/div><style>.ld_fancy_heading_6a046329c3305 p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329c3305 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329c3305 p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329c3305\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Nous diviserons l&rsquo;ensemble du groupe en petites \u00e9quipes. Ensuite, chaque \u00e9quipe recevra les instructions du jeu ainsi qu&rsquo;une carte, du mat\u00e9riel d&rsquo;\u00e9criture et au moins un appareil photo par groupe. Toutes les \u00e9quipes partent en m\u00eame temps, en partant du m\u00eame endroit, mais elles visiteront les diff\u00e9rents spots de d\u00e9fis dans un ordre diff\u00e9rent. \u00c0 la fin du parcours, toutes les \u00e9quipes se rassemblent au point d&rsquo;arriv\u00e9e.<\/p>\n<p>Pour s&rsquo;assurer que chaque \u00e9quipe r\u00e9ussisse toutes les places, elle doit accomplir certaines t\u00e2ches. Au cours de la visite \u00e0 pied, les \u00e9quipes doivent r\u00e9soudre des \u00e9nigmes, trouver la solution \u00e0 une \u00e9nigme, trouver un certain objet, trouver une l\u00e9gende ou une histoire, prendre des photos, etc&#8230; Un moniteur assiste l&rsquo;\u00e9quipe tout au long du parcours et surveille le parcours. bonne \u00e9volution de la tourn\u00e9e.<\/p>\n<p>Cette activit\u00e9 est tr\u00e8s flexible. Par exemple\u00a0: aller boire un verre et s&rsquo;arr\u00eater\u00a0pour\u00a0 manger des tapas, etc. Les circuits \u00e0 pied peuvent \u00e9galement \u00eatre modifi\u00e9s pour les rendre plus courts ou plus longs. Ils vous am\u00e8neront sur de belles places, rues, \u00e9glises et parcs et vous laisseront un excellent souvenir de la ville. Une journ\u00e9e inoubliable!<\/p><\/div><\/div><div id=\"lqd-1682100543635-94960ecb-75f1\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a046329c36f0 h5{color:#6ebb1f;}.ld_fancy_heading_6a046329c36f0 h5 {font-size:25px; } .ld_fancy_heading_6a046329c36f0 h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a046329c36f0 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329c36f0 h5 {font-size:25px; } .ld_fancy_heading_6a046329c36f0 h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329c36f0\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Atelier de flamenco<\/h5><\/div><style>.ld_content_box_6a046329c3a01 .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a046329c3a01\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a046329c3a01\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 700 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_flamenco_lesson2.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_flamenco_lesson2.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_flamenco_lesson2-300x129.jpeg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" data-aspect=\"2.3333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t<i class=\"fas fa-users\"><\/i>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 S\u00e9ville<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Atelier de flamenco<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a046329c68ca{height:30px;}@media (min-width: 992px) { .ld_spacer_6a046329c68ca{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a046329c68ca\"><\/div><style>.ld_fancy_heading_6a046329c6ac6 h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329c6ac6 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329c6ac6 h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329c6ac6\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <strong>Tout d&rsquo;abord, qu&rsquo;est-ce que le \u00ab flamenco \u00bb ? Le flamenco est un v\u00e9ritable art du sud de l&rsquo;Espagne et il existe sous trois formes : Cante &#8211; le chant, Baile &#8211; la danse et Guitarra &#8211; la guitare.<\/strong><\/h6><\/div><style>.ld_fancy_heading_6a046329c6d01 p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329c6d01 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329c6d01 p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329c6d01\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  \u00c9tant un \u00e9l\u00e9ment si important et passionnant de la tradition et de l\u2019histoire de S\u00e9ville, nous souhaitons proposer un cours collectif sp\u00e9cial de flamenco, disponible toute l\u2019ann\u00e9e. L&rsquo;objectif est de conna\u00eetre les mouvements de base tout en s&rsquo;amusant avec vos coll\u00e8gues. Ces cours sont con\u00e7us pour les besoins et les go\u00fbts sp\u00e9cifiques des participants qui nous rejoindront dans cette exp\u00e9rience. Le cours a une dur\u00e9e et une intensit\u00e9 variables, avec un minimum de 6 personnes. Les cours sont bas\u00e9s sur diff\u00e9rentes combinaisons possibles de technique, d&rsquo;enseignement de la danse et de cours de Comp\u00e1s &amp; Palmas &#8211; rythme flamenco et claquements de mains.<\/p>\n<p>En fonction du budget du groupe, nous pouvons \u00e9galement organiser la pr\u00e9sence d&rsquo;un guitariste et\/ou d&rsquo;un chanteur de flamenco qui permettra aux participants de profiter d&rsquo;une atmosph\u00e8re flamenco authentique en guise de spectacle parall\u00e8le, o\u00f9 l&rsquo;enseignement de la danse est pr\u00e9sent\u00e9 sur fond de notes d&rsquo;un guitare et le son des chants.<\/p>\n<p>Nous pouvons fournir des \u00e9ventails traditionnels de flamenco ou des castagnettes pour une chor\u00e9graphie finale et un souvenir de l&rsquo;activit\u00e9 !<\/p>\n<p>Nous vous proposerons ensuite d&rsquo;aller d\u00eener dans l&rsquo;un des meilleurs spectacles de flamenco de la ville o\u00f9 vous rencontrerez des professionnels et mettrez en pratique ce que vous avez appris pendant le cours.<\/p><\/div><\/div><div id=\"lqd-1682100880311-e775a2c7-a375\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a046329c6fa5 h5{color:#6ebb1f;}.ld_fancy_heading_6a046329c6fa5 h5 {font-size:25px; } .ld_fancy_heading_6a046329c6fa5 h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a046329c6fa5 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329c6fa5 h5 {font-size:25px; } .ld_fancy_heading_6a046329c6fa5 h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329c6fa5\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Faire du ballon ascensionnel<\/h5><\/div><style>.ld_content_box_6a046329c719b .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a046329c719b\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a046329c719b\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 700 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/hot-air-balloning.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/hot-air-balloning.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/hot-air-balloning-300x129.jpeg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" data-aspect=\"2.3333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 S\u00e9ville<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Faire du ballon ascensionnel<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a046329c9525{height:30px;}@media (min-width: 992px) { .ld_spacer_6a046329c9525{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a046329c9525\"><\/div><style>.ld_fancy_heading_6a046329c96d1 h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329c96d1 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329c96d1 h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329c96d1\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <\/p>\n<div id=\"intro\">\n<div id=\"intro\">\n<div id=\"intro\">\n<p><strong>Venez profiter de la ville depuis les hauteurs en participant \u00e0 une aventure inoubliable. Flottez doucement entre les nuages et admirez la vue sur les arbres, les champs de ma\u00efs et les jolis villages\u2026<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<p><\/h6><\/div><style>.ld_fancy_heading_6a046329c993c p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329c993c .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329c993c p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329c993c\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <em>Cette activit\u00e9 est prise en charge par l&rsquo;une des entreprises de montgolfi\u00e8res les plus fiables autoris\u00e9es par la Direction g\u00e9n\u00e9rale de l&rsquo;aviation civile et la Soci\u00e9t\u00e9 andalouse de tourisme de plein air, certifi\u00e9e I+E.<\/em><\/p>\n<p>Apr\u00e8s confirmation des bonnes conditions m\u00e9t\u00e9orologiques pour cette activit\u00e9, nous vous emm\u00e8nerons depuis votre h\u00f4tel \u00e0 S\u00e9ville jusqu&rsquo;au point de rendez-vous \u00e0 environ 25 minutes du centre ville. Le vol d\u00e9butera vers 7h-8h, trente minutes avant le lever du soleil. Nous nous rendrons \u00e0 l&rsquo;a\u00e9rodrome avec les v\u00e9hicules de soci\u00e9t\u00e9 mis \u00e0 disposition. Ensuite, nous d\u00e9couvrirons le monde de la montgolfi\u00e8re, avec une explication des r\u00e8gles de base et des dispositifs techniques de s\u00e9curit\u00e9.<\/p>\n<p>Avec l&rsquo;aide des participants, nous commencerons \u00e0 pr\u00e9parer la montgolfi\u00e8re. Trente\u00a0minutes pour le gonflage du ballon, la prise de photos et de vid\u00e9os, le pilote allumera les chauffages et la montgolfi\u00e8re est pr\u00eate pour que nous puissions y monter, mettre nos chapeaux volants et nous lancer dans notre aventure &#8211; Up, Up et Loin!<\/p>\n<p>En fonction de la direction du vent, nous survolerons le Corredor Verde del Guadiamar, l&rsquo;Aljarafe s\u00e9villane, les Pinares de Aznalcazar ou Chucena et la zone du parc naturel de Do\u00f1ana. Le vol durera environ 70 \u00e0 90 minutes et le pilote identifiera le meilleur endroit pour atterrir.<\/p>\n<p>Une fois atterris, nous offrirons des rafra\u00eechissements aux participants puis nous nous dirigerons vers la zone r\u00e9serv\u00e9e de l&rsquo;h\u00f4tel voisin pour un petit-d\u00e9jeuner buffet andalou, o\u00f9 nous ferons le d\u00e9briefing entre les participants et les pilotes.<\/p><\/div><\/div><div id=\"lqd-1682098856421-82b74996-23ce\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a046329c9be6 h5{color:#6ebb1f;}.ld_fancy_heading_6a046329c9be6 h5 {font-size:25px; } .ld_fancy_heading_6a046329c9be6 h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a046329c9be6 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329c9be6 h5 {font-size:25px; } .ld_fancy_heading_6a046329c9be6 h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329c9be6\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Grand Prix Moto de Jerez<\/h5><\/div><style>.ld_content_box_6a046329c9dc3 .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a046329c9dc3\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a046329c9dc3\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"640\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 640 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_motoGP_640_300_c1_c_t_0_0-1.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_motoGP_640_300_c1_c_t_0_0-1.jpeg 640w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_motoGP_640_300_c1_c_t_0_0-1-300x141.jpeg 300w\" data-sizes=\"(max-width: 640px) 100vw, 640px\" data-aspect=\"2.1333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t<i class=\"fas fa-motorcycle\"><\/i>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 S\u00e9ville<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Grand Prix Moto de Jerez<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a046329d4f4e{height:30px;}@media (min-width: 992px) { .ld_spacer_6a046329d4f4e{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a046329d4f4e\"><\/div><style>.ld_fancy_heading_6a046329d50f7 h6 {margin-bottom:1em !important;  } .ld_fancy_heading_6a046329d50f7 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329d50f7 h6 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329d50f7\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <\/p>\n<div id=\"intro\">\n<p><strong>Enyevent DMC est passionn\u00e9e par les \u00e9v\u00e9nements sportifs, surtout lorsqu&rsquo;ils se d\u00e9roulent dans l&rsquo;une de nos destinations. Profitez-en pour organiser une r\u00e9union de groupe, un voyage de motivation d&rsquo;entreprise, une visite technique ou une r\u00e9union entre amis pendant le Moto GP de Jerez et vous aurez l&rsquo;occasion d&rsquo;allier affaires, culture et loisirs.<\/strong><\/p>\n<\/div>\n<p><\/h6><\/div><style>.ld_fancy_heading_6a046329d5366 p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329d5366 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329d5366 p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329d5366\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Le Moto GP Jerez se d\u00e9roule chaque ann\u00e9e dans la provence de Cadix, pr\u00e8s de S\u00e9ville. Son circuit est le th\u00e9\u00e2tre de cette course, et re\u00e7oit de nombreuses manifestations sportives tout au long de l&rsquo;ann\u00e9e.<\/p>\n<p>Cet \u00e9v\u00e9nement rassemble des motocyclistes internationaux en comp\u00e9tition pour remporter le Prix Moto GP et a inscrit Jerez sur la carte des \u00e9v\u00e9nements majeurs, attirant des milliers de fans qui suivent intens\u00e9ment les r\u00e9sultats de leurs idoles sportives. Ces comp\u00e9titions se d\u00e9roulent dans des cadres uniques, qui donnent un \u00e9clat particulier au timing des villes h\u00f4tes&#8230;<\/p>\n<p>D\u00e9couvrez les virages \u00e0 couper le souffle du Circuit qui vous permettront de vivre un rythme effr\u00e9n\u00e9, de faire le plein de sensations fortes et de permettre \u00e0 votre \u00e9quipe de voyager\u00a0 entre un environnement motard et la ville culturelle de Jerez et de S\u00e9ville. Le Moto GP Jerez rassemble l&rsquo;\u00e9lite des pilotes moto internationaux pour garantir un niveau de comp\u00e9tition et de course exceptionnellement \u00e9lev\u00e9.<\/p>\n<p>Enyevent DMC s&rsquo;occupe de tout le week-end, en r\u00e9servant l&rsquo;h\u00e9bergement ad\u00e9quat, les transferts locaux de luxe n\u00e9cessaires et tous les autres services qui cr\u00e9eront un programme complet et int\u00e9ressant lors de ces \u00e9v\u00e9nements sportifs. Combinez-le avec une activit\u00e9 de voile, une d\u00e9gustation de vin ou une visite \u00e0 v\u00e9lo et profitez de la vie nocturne anim\u00e9e de S\u00e9ville dans les restaurants et clubs branch\u00e9s.<\/p>\n<p>Combinez l\u2019\u00e9nergie de la course automobile et l\u2019authenticit\u00e9 de l\u2019ambiance m\u00e9diterran\u00e9enne locale pour un \u00e9v\u00e9nement inoubliable.<\/p><\/div><\/div><div id=\"lqd-1682101913122-39af1888-036a\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a046329d5615 h5{color:#6ebb1f;}.ld_fancy_heading_6a046329d5615 h5 {font-size:25px; } .ld_fancy_heading_6a046329d5615 h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a046329d5615 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329d5615 h5 {font-size:25px; } .ld_fancy_heading_6a046329d5615 h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329d5615\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Visite en Segway<\/h5><\/div><style>.ld_content_box_6a046329d57f4 .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a046329d57f4\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a046329d57f4\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 700 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_segway_seville.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_segway_seville.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_segway_seville-300x129.jpeg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" data-aspect=\"2.3333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 S\u00e9ville<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Visite en Segway<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a046329d7c3b{height:30px;}@media (min-width: 992px) { .ld_spacer_6a046329d7c3b{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a046329d7c3b\"><\/div><style>.ld_fancy_heading_6a046329d7def h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329d7def .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329d7def h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329d7def\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <\/p>\n<div id=\"intro\">\n<div id=\"intro\">\n<p><strong>Si vous souhaitez d\u00e9couvrir la ville sur roues, l&rsquo;alternative est d&rsquo;organiser une visite en Segway. Les participants profiteront de la vue sur la vieille ville historique, parcourront les rues \u00e9troites et les places cach\u00e9es, vivront l&rsquo;exp\u00e9rience des autochtones, de mani\u00e8re relaxante et amusante.<\/strong><\/p>\n<\/div>\n<\/div>\n<p><\/h6><\/div><style>.ld_fancy_heading_6a046329d805e p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329d805e .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329d805e p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329d805e\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  L&rsquo;activit\u00e9 commencera par un briefing sur le fonctionnement du Segway par l&rsquo;un des moniteurs. Ceci est ensuite suivi d&rsquo;une pratique de formation pour chaque participant, qui durera environ 15 minutes. Apr\u00e8s cela, nous commencerons la visite et nous fournirons un plan de la ville pour que tout le monde puisse s&rsquo;orienter avant de partir.<\/p>\n<p>Il existe de nombreux itin\u00e9raires disponibles, d&rsquo;une dur\u00e9e d&rsquo;une heure \u00e0 deux heures. Vous pouvez choisir parmi\u00a0:<br \/>\n<strong>S\u00e9ville Monumentale<\/strong>\u00a0: Un parcours de deux heures commen\u00e7ant par l&rsquo;entra\u00eenement et depuis les jardins de Murillo, puis vous vous dirigerez vers les jardins du Prado, en entrant sur la Plaza de Espa\u00f1a et le parc Mar\u00eda Luisa, le long du fleuve Guadalquivir, o\u00f9 vous verrez la Tour d&rsquo;Or. De l\u00e0, vous continuerez vers le palais de San Telmo, la Puerta de Jerez, en arrivant au magnifique site de la cath\u00e9drale, de la GIralda et de l&rsquo;Alcazar et enfin\u00a0en terminant au quartier juif et de Santa Cruz.<\/p>\n<p><strong>Triana<\/strong>\u00a0\u00a0: un parcours de 4,5\u00a0km au d\u00e9part de la Plaza Santa Cruz. Vous longerez le fleuve Guadalquivir en direction de la Plaza de Cuba o\u00f9 vous passerez par la c\u00e9l\u00e8bre rue Betis, l&rsquo;\u00e9glise de Santa Ana, puis vous longerez le Paseo de la Virgen \u00e0 c\u00f4t\u00e9 du fleuve pour arriver au Callejon de la Inquisici\u00f3n. , o\u00f9 se d\u00e9roulera une visite de l&rsquo;int\u00e9rieur du quartier o\u00f9 vous pourrez vous arr\u00eater pour visiter une boutique de c\u00e9ramique et revenir au point de d\u00e9part pr\u00e8s du march\u00e9 et du pont de Triana.<\/p>\n<p>Comme pour toute autre activit\u00e9, nous serons ravis d&rsquo;organiser une halte tapas, un d\u00e9jeuner traditionnel ou simplement d&rsquo;aller prendre un verre pour nous asseoir et profiter du rythme de la ville.<\/p><\/div><\/div><div id=\"lqd-1682101131837-cc7a49bc-07e6\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a046329d833d h5{color:#6ebb1f;}.ld_fancy_heading_6a046329d833d h5 {font-size:25px; } .ld_fancy_heading_6a046329d833d h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a046329d833d .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329d833d h5 {font-size:25px; } .ld_fancy_heading_6a046329d833d h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329d833d\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Visites et excursions<\/h5><\/div><style>.ld_content_box_6a046329d8541 .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a046329d8541\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a046329d8541\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 700 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_sevilla_tours.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_sevilla_tours.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_sevilla_tours-300x129.jpeg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" data-aspect=\"2.3333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t<i class=\"fas fa-location-arrow\"><\/i>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 S\u00e9ville<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Visites et excursions<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a046329dab91{height:30px;}@media (min-width: 992px) { .ld_spacer_6a046329dab91{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a046329dab91\"><\/div><style>.ld_fancy_heading_6a046329dad45 h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329dad45 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329dad45 h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329dad45\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <\/p>\n<div id=\"intro\">\n<p><strong>Enyevent DMC propose \u00e0 votre \u00e9quipe un choix de circuits et excursions sur mesure \u00e0 S\u00e9ville.<\/strong><\/p>\n<\/div>\n<p><\/h6><\/div><style>.ld_fancy_heading_6a046329daf86 p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329daf86 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329daf86 p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329daf86\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <strong>Se promener dans le centre historique de S\u00e9ville<\/strong>\u00a0: Si vous disposez d&rsquo;une demi-journ\u00e9e pour d\u00e9couvrir S\u00e9ville, nous vous proposons de visiter la cath\u00e9drale et la Giralda, l&rsquo;Alcazar et le quartier juif du Barrio Santa Cruz. Pour rendre ce tour plus unique, nous pouvons \u00e9galement r\u00e9server les cal\u00e8ches traditionnelles et vous pouvez faire un tour pour une balade panoramique entre les deux\u2026 !<\/p>\n<p><strong>S\u00e9ville Monumentale\u00a0<\/strong>: Une excursion d&rsquo;une demi-journ\u00e9e pour visiter la Plaza de Espa\u00f1a, probablement la plus belle d&rsquo;Espagne, situ\u00e9e dans le Parque Maria Luisa. Vous verrez \u00e9galement le fleuve Guadalquivir, le Golden Tour et bien s\u00fbr les ar\u00e8nes de S\u00e9ville sur la Plaza de Toros.<br \/>\nNous vous laisserons pr\u00e8s de la belle cath\u00e9drale que vous visiterez avec votre guide avant de continuer vers l&rsquo;Alcazar. Vous pourrez ensuite d\u00e9ambuler dans les rues \u00e9troites du Barrio Santa Cruz, le quartier juif de la ville. La visite se terminera \u00e0 votre restaurant de d\u00e9jeuner ou \u00e0 l&rsquo;h\u00f4tel s\u00e9lectionn\u00e9.<\/p>\n<p><strong>Croisi\u00e8re artistique et fluviale \u00e0 S\u00e9ville<\/strong>\u00a0: cette excursion d&rsquo;une demi-journ\u00e9e se concentrera sur les principales attractions de la ville. Elle se poursuivra par une promenade en bateau sur le Guadalquivir qui navigue le long du fleuve. Vous b\u00e9n\u00e9ficierez de vues spectaculaires sur la ville et naviguerez le long des pavillons du site de l&rsquo;Expo 1992.<br \/>\nLa visite comprend \u00e9galement une visite de la magnifique basilique de Macarena et de la Chartreuse o\u00f9 Colomb a pass\u00e9 une grande partie de son temps.<\/p>\n<p><strong>S\u00e9ville la nuit et d\u00eener-spectacle de flamenco<\/strong>\u00a0\u00a0:\u00a0vous commencerez cette soir\u00e9e par une visite nocturne sp\u00e9ciale, avec un bus de luxe et votre guide priv\u00e9, de certains des principaux sites touristiques de la ville et de ses fontaines illumin\u00e9es avant de vous diriger vers l&rsquo;un des c\u00e9l\u00e8bres \u00ab tablaos flamenco \u00bb de S\u00e9ville. . Ici, vous assisterez \u00e0 un spectacle de danse flamenco espagnole tout en savourant un splendide d\u00eener.<\/p>\n<p><strong>Excursion \u00e0 Cordoue<\/strong>\u00a0: \u00c0 notre arriv\u00e9e \u00e0 Cordoue, nous commencerons \u00e0 explorer ses tr\u00e9sors les plus pr\u00e9cieux en commen\u00e7ant par le majestueux Alcazar de los Reyes Cristianos. Ensuite, en nous plongeant dans la beaut\u00e9 de la Mezquita, un t\u00e9moignage spectaculaire de l&rsquo;\u00e9poque californienne, nous partirons \u00e0 pied et explorerons le glorieux quartier juif de Cordoue. Nous parcourrons ses rues les plus embl\u00e9matiques comme la \u00ab Callej\u00f3n de las Flores \u00bb, une pure joie pour les sens, jusqu&rsquo;\u00e0 atteindre la place de los Gran Maimonides, o\u00f9 nous nous arr\u00eaterons pour visiter la Sinagogue.<\/p>\n<p>Ces visites comprennent un bus de luxe et climatis\u00e9, ainsi qu&rsquo;un guide officiel multilingue qui vous fera visiter le centre de S\u00e9ville \u00e0 pied.<\/p><\/div><\/div><div id=\"lqd-1682101311230-40f07417-99ab\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a046329db273 h5{color:#6ebb1f;}.ld_fancy_heading_6a046329db273 h5 {font-size:25px; } .ld_fancy_heading_6a046329db273 h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a046329db273 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329db273 h5 {font-size:25px; } .ld_fancy_heading_6a046329db273 h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329db273\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Tapas sautillantes<\/h5><\/div><style>.ld_content_box_6a046329db470 .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a046329db470\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a046329db470\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 700 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_tapas1.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_tapas1.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_tapas1-300x129.jpeg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" data-aspect=\"2.3333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t<i class=\"fas fa-utensils\"><\/i>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 S\u00e9ville<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Tapas sautillantes<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a046329dd859{height:30px;}@media (min-width: 992px) { .ld_spacer_6a046329dd859{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a046329dd859\"><\/div><style>.ld_fancy_heading_6a046329dd9f1 h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329dd9f1 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329dd9f1 h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329dd9f1\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <strong>Nous ne voulons pas que vous manquiez les c\u00e9l\u00e8bres tapas et \u00ab ir de tapeo \u00bb ! On attribue \u00e0 la ville l&rsquo;invention des tapas et compte des milliers de bars \u00e0 tapas o\u00f9 le choix de nourriture est tr\u00e8s large. Nous aimerions vous montrer comment les S\u00e9villans en pr\u00e9parent un repas, en passant de bar en bar et en d\u00e9gustant une s\u00e9rie de petits plats de nourriture. Partagez l&rsquo;exp\u00e9rience avec nous !<\/strong><\/h6><\/div><style>.ld_fancy_heading_6a046329ddc36 p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329ddc36 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329ddc36 p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329ddc36\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Un ou plusieurs guides locaux accompagneront les participants en un ou plusieurs groupes selon sa taille. Vous suivrez nos guides pour une visite \u00e0 pied du centre historique vers midi ou le soir tandis que vous vous arr\u00eaterez dans trois \u00e9tablissements anim\u00e9s diff\u00e9rents, bars en plein air ou terrasses pour \u00ab picar \u00bb (go\u00fbter) le plus de plats possible du s\u00e9lection de plats large et vari\u00e9e : salades, gaspacho, salmorejo, hachis de porc, l&rsquo;exquis jambon des Sierras de Huelva, les crevettes de Sanl\u00facar et le poisson frit.<\/p>\n<p>Ces d\u00e9lices sont accompagn\u00e9s de vins locaux, de x\u00e9r\u00e8s ou de bi\u00e8re dor\u00e9e. Nos clients recevront une carte d&rsquo;itin\u00e9raire et disposeront d&rsquo;un choix de tapas pr\u00e9-r\u00e9serv\u00e9 dans chacun des bars choisis. Les zones que nous explorerons seront principalement les quartiers de Santa Cruz, Triana et Arenal.<\/p>\n<p>\u00c0 la fin de l&rsquo;activit\u00e9, vous aurez d\u00e9couvert la cuisine s\u00e9villane authentique, la tradition culinaire, les anecdotes de la ville et les principales attractions que cette charmante ville a \u00e0 offrir.<\/p><\/div><\/div><div id=\"lqd-1682195028895-7c3f8ae9-d48c\" role=\"tabpanel\" class=\"lqd-tabs-pane fade\"><style>.ld_fancy_heading_6a046329ddec9 h5{color:#6ebb1f;}.ld_fancy_heading_6a046329ddec9 h5 {font-size:25px; } .ld_fancy_heading_6a046329ddec9 h5 {margin-bottom:1em !important;  } .ld_fancy_heading_6a046329ddec9 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329ddec9 h5 {font-size:25px; } .ld_fancy_heading_6a046329ddec9 h5 {margin-bottom:1em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329ddec9\">\n\t<h5 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Rallye 4&#215;4 dans la Sierra Norte<\/h5><\/div><style>.ld_content_box_6a046329de0a9 .lqd-fb-bg{background:-webkit-linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);background:linear-gradient(180deg, rgba(255, 255, 255, 0) 0%, rgba(24, 27, 49, 0.6) 100%);}<\/style><div id=\"ld_content_box_6a046329de0a9\" class=\"lqd-fb round h-pt-60 lqd-fb-style-6 pos-rel ld_content_box_6a046329de0a9\" data-lqd-zindex=\"true\">\n\t<div class=\"lqd-fb-inner lqd-overlay\">\n\t\t\n\t\t<div class=\"lqd-fb-shadow\"><\/div>\n\n\t\t<div class=\"d-flex flex-wrap align-items-center lqd-overlay\" data-hover3d=\"true\">\n\n\t\t\t<div class=\"lqd-fb-content-wrap lqd-overlay flex-column align-items-end transform-style-3d backface-hidden will-change-transform\" data-stacking-factor=\"0.5\">\n\n\t\t\t\t<div class=\"lqd-fb-img lqd-overlay rount backface-hidden\">\n\t\t\t\t\t<figure class=\"w-100\" data-responsive-bg=\"true\">\n\t\t\t\t\t\t<img decoding=\"async\" width=\"700\" height=\"300\" src=\"data:image\/svg+xml;charset=utf-8,%3Csvg xmlns%3D&#039;http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg&#039; viewBox%3D&#039;0 0 700 300&#039;%2F%3E\" class=\"w-100 invisible ld-lazyload\" alt=\"\" itemprop=\"image\" data-src=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_4x4-seville.jpeg\" data-srcset=\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_4x4-seville.jpeg 700w, https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/Enyevent_4x4-seville-300x129.jpeg 300w\" data-sizes=\"(max-width: 700px) 100vw, 700px\" data-aspect=\"2.3333333333333\" \/>\t\t\t\t\t<\/figure>\n\t\t\t\t\t<div class=\"lqd-fb-bg lqd-overlay\"><\/div>\n\t\t\t\t\t<div class=\"lqd-fb-hover-overlay lqd-overlay\"><\/div>\n\t\t\t\t<\/div>\n\n\t\t\t\t<div class=\"lqd-fb-content pos-abs pos-bl w-100 p-4 py-lg-7 px-lg-8 backface-hidden\">\n\n\t\t\t\t\t<span class=\"lqd-fb-icon d-flex mb-5\">\n\t\t\t\t\t\t<i class=\"fas fa-car-side\"><\/i>\t\t\t\t\t<\/span>\n\n\t\t\t\t\t\t\t\t\t\t<h6 class=\"my-0 mb-3 font-weight-bold text-uppercase ltr-sp-2\">Activit\u00e9s \u00e0 S\u00e9ville<\/h6>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t<h2 class=\"lqd-fb-content-title my-0 mb-3 font-weight-bold\">Rallye 4x4 dans la Sierra Norte<\/h2>\n\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\n\t\t\t\t<\/div>\n\n\t\t\t\t\n\t\t\t<\/div>\n\n\t\t<\/div>\n\n\t<\/div>\n<\/div><style>.ld_spacer_6a046329e045a{height:30px;}@media (min-width: 992px) { .ld_spacer_6a046329e045a{height:45px};}<\/style>\n<div class=\"ld-empty-space ld_spacer_6a046329e045a\"><\/div><style>.ld_fancy_heading_6a046329e061c h6 {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329e061c .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329e061c h6 {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329e061c\">\n\t<h6 class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  <strong>Cette activit\u00e9 s&rsquo;adresse \u00e0 ceux qui souhaitent profiter au maximum de l&rsquo;aventure des sentiers naturels. Depuis S\u00e9ville, nous visiterons la Sierra du Nord en v\u00e9hicules 4&#215;4 et terminerons notre beau voyage par une exp\u00e9rience \u00e0 v\u00e9lo \u00e0 travers for\u00eats et rivi\u00e8res.<\/strong><\/h6><\/div><style>.ld_fancy_heading_6a046329e0841 p {margin-bottom:1.5em !important;  } .ld_fancy_heading_6a046329e0841 .lqd-highlight-inner{height:0.275em!important;bottom:0px!important;}.ld_fancy_heading_6a046329e0841 p {margin-bottom:1.5em !important;  } <\/style><div class=\"ld-fancy-heading ld_fancy_heading_6a046329e0841\">\n\t<p class=\"ld-fh-element lqd-highlight-underline lqd-highlight-grow-left text-decoration-default\"   >  Le parcours 4&#215;4 est con\u00e7u pour qu&rsquo;\u00e0 travers les routes sinueuses de cette belle r\u00e9gion, les participants puissent avoir un contact direct avec la nature et d\u00e9couvrir tous les secrets du paysage et de la soci\u00e9t\u00e9 des gens qui y vivent. Le parcours 4&#215;4 dure une demi-journ\u00e9e.<\/p>\n<p>Nous nous arr\u00eaterons pour un pique-nique \u00e0 la campagne puis changerons de v\u00e9hicule\u2026 et maintenant, si vous le souhaitez, nous continuerons \u00e0 v\u00e9lo !<\/p>\n<p>Dans la Sierra Norte de S\u00e9ville, parmi tous ces secrets du paysage local, il y a de tr\u00e8s nombreux aspects int\u00e9ressants de la nature \u00e0 d\u00e9couvrir. La piste cyclable nous prendra environ deux heures.<\/p>\n<p>Nous inclurons pour cette activit\u00e9 tous les v\u00e9hicules n\u00e9cessaires (4&#215;4 et v\u00e9los), un roadbook, des talkie-walkies, un kit collations et eau, le pique-nique, l&rsquo;assurance et les autorisations, ainsi que les moniteurs qualifi\u00e9s et tout notre d\u00e9vouement pour faire de ce voyage un moment inoubliable. pour vous et vos invit\u00e9s !<\/p><\/div><\/div><\/div>\n<\/div>\n[\/vc_column][\/vc_row]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":4925,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-4877","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Seville - Enyevent<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enyevent.com\/es\/destinos\/seville\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Seville - Enyevent\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enyevent.com\/es\/destinos\/seville\/\" \/>\n<meta property=\"og:site_name\" content=\"Enyevent\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pages\/Enyevent-Solutions\/1429727033923570\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-19T19:44:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@EnyeventSL\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"22 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/enyevent.com\/es\/destinos\/seville\/\",\"url\":\"https:\/\/enyevent.com\/es\/destinos\/seville\/\",\"name\":\"Seville - Enyevent\",\"isPartOf\":{\"@id\":\"https:\/\/enyevent.com\/#website\"},\"datePublished\":\"2023-04-22T20:16:36+00:00\",\"dateModified\":\"2024-03-19T19:44:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/enyevent.com\/es\/destinos\/seville\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/enyevent.com\/es\/destinos\/seville\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/enyevent.com\/es\/destinos\/seville\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/enyevent.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gestion des destinations\",\"item\":\"https:\/\/enyevent.com\/es\/destinos\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Seville\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/enyevent.com\/#website\",\"url\":\"https:\/\/enyevent.com\/\",\"name\":\"Enyevent\",\"description\":\"DMC Spain and France - Event planner in Spain and France\",\"publisher\":{\"@id\":\"https:\/\/enyevent.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/enyevent.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/enyevent.com\/#organization\",\"name\":\"Enyevent\",\"url\":\"https:\/\/enyevent.com\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/enyevent.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/logo-enyevent.png\",\"contentUrl\":\"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/logo-enyevent.png\",\"width\":226,\"height\":71,\"caption\":\"Enyevent\"},\"image\":{\"@id\":\"https:\/\/enyevent.com\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/pages\/Enyevent-Solutions\/1429727033923570\",\"https:\/\/x.com\/EnyeventSL\",\"https:\/\/www.instagram.com\/enyeventspaindmc\",\"http:\/\/www.youtube.com\/channel\/UCDehJbTpYupuXUgSye4jxjA\/about\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Seville - Enyevent","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enyevent.com\/es\/destinos\/seville\/","og_locale":"fr_FR","og_type":"article","og_title":"Seville - Enyevent","og_description":"[vc_row][vc_column][\/vc_column][\/vc_row]","og_url":"https:\/\/enyevent.com\/es\/destinos\/seville\/","og_site_name":"Enyevent","article_publisher":"https:\/\/www.facebook.com\/pages\/Enyevent-Solutions\/1429727033923570","article_modified_time":"2024-03-19T19:44:15+00:00","twitter_card":"summary_large_image","twitter_site":"@EnyeventSL","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"22 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/enyevent.com\/es\/destinos\/seville\/","url":"https:\/\/enyevent.com\/es\/destinos\/seville\/","name":"Seville - Enyevent","isPartOf":{"@id":"https:\/\/enyevent.com\/#website"},"datePublished":"2023-04-22T20:16:36+00:00","dateModified":"2024-03-19T19:44:15+00:00","breadcrumb":{"@id":"https:\/\/enyevent.com\/es\/destinos\/seville\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enyevent.com\/es\/destinos\/seville\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/enyevent.com\/es\/destinos\/seville\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/enyevent.com\/es\/"},{"@type":"ListItem","position":2,"name":"Gestion des destinations","item":"https:\/\/enyevent.com\/es\/destinos\/"},{"@type":"ListItem","position":3,"name":"Seville"}]},{"@type":"WebSite","@id":"https:\/\/enyevent.com\/#website","url":"https:\/\/enyevent.com\/","name":"Enyevent","description":"DMC Spain and France - Event planner in Spain and France","publisher":{"@id":"https:\/\/enyevent.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enyevent.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/enyevent.com\/#organization","name":"Enyevent","url":"https:\/\/enyevent.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/enyevent.com\/#\/schema\/logo\/image\/","url":"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/logo-enyevent.png","contentUrl":"https:\/\/enyevent.com\/wp-content\/uploads\/2023\/04\/logo-enyevent.png","width":226,"height":71,"caption":"Enyevent"},"image":{"@id":"https:\/\/enyevent.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pages\/Enyevent-Solutions\/1429727033923570","https:\/\/x.com\/EnyeventSL","https:\/\/www.instagram.com\/enyeventspaindmc","http:\/\/www.youtube.com\/channel\/UCDehJbTpYupuXUgSye4jxjA\/about"]}]}},"_links":{"self":[{"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/pages\/4877"}],"collection":[{"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/comments?post=4877"}],"version-history":[{"count":4,"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/pages\/4877\/revisions"}],"predecessor-version":[{"id":5700,"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/pages\/4877\/revisions\/5700"}],"up":[{"embeddable":true,"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/pages\/4925"}],"wp:attachment":[{"href":"https:\/\/enyevent.com\/fr\/wp-json\/wp\/v2\/media?parent=4877"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}